{"id":1675,"date":"2020-07-15T19:56:23","date_gmt":"2020-07-15T13:56:23","guid":{"rendered":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png"},"modified":"2020-07-15T19:56:40","modified_gmt":"2020-07-15T13:56:40","slug":"uptrends","status":"inherit","type":"attachment","link":"https:\/\/www.vernalweb.com\/blog\/website-speed-test-tools\/uptrends\/","title":{"rendered":"uptrends"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1675","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>uptrends - VernalWeb Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"uptrends - VernalWeb Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png\" \/>\n<meta property=\"og:site_name\" content=\"VernalWeb Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VernalWeb\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-15T13:56:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1235\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@VernalWeb\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/uptrends.png\",\"url\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/uptrends.png\",\"name\":\"uptrends - VernalWeb Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/#website\"},\"datePublished\":\"2020-07-15T13:56:23+00:00\",\"dateModified\":\"2020-07-15T13:56:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/uptrends.png#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/uptrends.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/uptrends.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 10 Free Website Speed Test Tools in 2025\",\"item\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/website-speed-test-tools\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"uptrends\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/\",\"name\":\"VernalWeb Blog\",\"description\":\"Learn the Secrets of Boosting Your Website &amp; Business\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/#organization\",\"name\":\"VernalWeb\",\"url\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo.png\",\"width\":200,\"height\":35,\"caption\":\"VernalWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vernalweb.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VernalWeb\\\/\",\"https:\\\/\\\/x.com\\\/VernalWeb\",\"https:\\\/\\\/www.instagram.com\\\/vernal.web\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vernalweb\",\"https:\\\/\\\/www.pinterest.com\\\/vernalweb\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBvOA1kxAjr2nPN1uMRYMSQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"uptrends - VernalWeb Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png","og_locale":"en_US","og_type":"article","og_title":"uptrends - VernalWeb Blog","og_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png","og_site_name":"VernalWeb Blog","article_publisher":"https:\/\/www.facebook.com\/VernalWeb\/","article_modified_time":"2020-07-15T13:56:40+00:00","og_image":[{"width":1235,"height":655,"url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@VernalWeb","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png","url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png","name":"uptrends - VernalWeb Blog","isPartOf":{"@id":"https:\/\/www.vernalweb.com\/blog\/#website"},"datePublished":"2020-07-15T13:56:23+00:00","dateModified":"2020-07-15T13:56:40+00:00","breadcrumb":{"@id":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vernalweb.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 10 Free Website Speed Test Tools in 2025","item":"https:\/\/www.vernalweb.com\/blog\/website-speed-test-tools\/"},{"@type":"ListItem","position":3,"name":"uptrends"}]},{"@type":"WebSite","@id":"https:\/\/www.vernalweb.com\/blog\/#website","url":"https:\/\/www.vernalweb.com\/blog\/","name":"VernalWeb Blog","description":"Learn the Secrets of Boosting Your Website &amp; Business","publisher":{"@id":"https:\/\/www.vernalweb.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vernalweb.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.vernalweb.com\/blog\/#organization","name":"VernalWeb","url":"https:\/\/www.vernalweb.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vernalweb.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2019\/08\/logo.png","contentUrl":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2019\/08\/logo.png","width":200,"height":35,"caption":"VernalWeb"},"image":{"@id":"https:\/\/www.vernalweb.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VernalWeb\/","https:\/\/x.com\/VernalWeb","https:\/\/www.instagram.com\/vernal.web\/","https:\/\/www.linkedin.com\/company\/vernalweb","https:\/\/www.pinterest.com\/vernalweb\/","https:\/\/www.youtube.com\/channel\/UCBvOA1kxAjr2nPN1uMRYMSQ"]}]}},"has_video":false,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"159\" src=\"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-300x159.png\" class=\"attachment-medium size-medium\" alt=\"Uptrends\" srcset=\"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-300x159.png 300w, https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-1024x543.png 1024w, https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-768x407.png 768w, https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png 1235w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Uptrends","media_type":"image","mime_type":"image\/png","media_details":{"width":1235,"height":655,"file":"2016\/09\/uptrends.png","sizes":{"medium":{"file":"uptrends-300x159.png","width":300,"height":159,"mime_type":"image\/png","source_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-300x159.png"},"large":{"file":"uptrends-1024x543.png","width":1024,"height":543,"mime_type":"image\/png","source_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-1024x543.png"},"thumbnail":{"file":"uptrends-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-150x150.png"},"medium_large":{"file":"uptrends-768x407.png","width":768,"height":407,"mime_type":"image\/png","source_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends-768x407.png"},"full":{"file":"uptrends.png","width":1235,"height":655,"mime_type":"image\/png","source_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":152,"source_url":"https:\/\/www.vernalweb.com\/blog\/wp-content\/uploads\/2016\/09\/uptrends.png","_links":{"self":[{"href":"https:\/\/www.vernalweb.com\/blog\/wp-json\/wp\/v2\/media\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vernalweb.com\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.vernalweb.com\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.vernalweb.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vernalweb.com\/blog\/wp-json\/wp\/v2\/comments?post=1675"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":152,"href":"https:\/\/www.vernalweb.com\/blog\/wp-json\/wp\/v2\/posts\/152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}